{"id":6916,"date":"2019-02-05T13:30:40","date_gmt":"2019-02-05T12:30:40","guid":{"rendered":"http:\/\/www.gonzaloanaya.com\/es\/?p=6916"},"modified":"2019-02-05T13:30:40","modified_gmt":"2019-02-05T12:30:40","slug":"junta-trabajando-por-escuela-inclusiva","status":"publish","type":"post","link":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/","title":{"rendered":"La junta, trabajando por la escuela inclusiva"},"content":{"rendered":"<p>La junta directiva se reuni\u00f3 este fin de semana para tratar temas que preocupan a las familias de la escuela p\u00fablica. Como punto central, la inclusi\u00f3n y la nueva ley.\u00a0Queremos una escuela inclusiva real.<\/p>\n<p>Desde de la Confederaci\u00f3n Gonzalo\u00a0Anaya consideramos que todos los ni\u00f1os y ni\u00f1as tienen derecho a una educaci\u00f3n p\u00fablica de calidad. Las asociaciones de padres y madres nos hacen llegar quejas concretas sobre la falta de recursos en los centros ordinarios para atender los que necesitan m\u00e1s apoyos. Uno de los puntos en los cuales hemos insistido en los \u00faltimos a\u00f1os es la falta de educadores para las aulas\u00a0CYL\u00a0en las tres provincias. Los plazos para cubrir las plazas son demasiado largos para unos ni\u00f1os y ni\u00f1as que necesitan atenci\u00f3n contin\u00faa. Adem\u00e1s, el alta rotaci\u00f3n de los profesionales que est\u00e1n en estas aulas hace dif\u00edcil el avance del alumnado, m\u00e1xime cuando la mayor\u00eda se encuentran dentro del trastorno del espectro autista, y precisamente el que m\u00e1s necesitan son rutinas y un personal estable para aportarlos seguridad y poder avanzar.<\/p>\n<p>\u201cLa integraci\u00f3n del\u00a0alumnado que necesita m\u00e1s apoyo no puede quedarse escrito en un papel como es el decreto y la nueva orden de inclusi\u00f3n, tiene que ser real en cada centro de ense\u00f1anza p\u00fablica, con los recursos que sean necesarios. No puede haber un desequilibrio entre los centros que apuestan por la inclusi\u00f3n y los que no lo hacen. Nos encontramos en todo el territorio valenciano, en las tres provincias, centros desbordados por el n\u00famero de alumnado que necesitan apoyo curricular, mientras otros centros no los tienen a este alumnado matriculados. En la provincia de Alicante y en comarcas concretas de Valencia como La Safor o La Ribera, nos encontramos claros ejemplos.\u201d, indica el presidente de Gonzalo\u00a0Anaya, Txomin\u00a0Ang\u00f3s.<\/p>\n<p>Otro tema importante que hemos detectado y en el cual queremos insistir es en el salto que hay respeto en los apoyos educativos de la educaci\u00f3n primaria a la secundaria. La normativa habla de inclusi\u00f3n en toda la educaci\u00f3n obligatoria, pero bien es verdad que para el alumnado de las aulas\u00a0CYL\u00a0se inicia una etapa de incertidumbre cuando llegan a secundaria. Posamos como ejemplo la voz de alarma que han levantado las familias de la comarca de Camp de Morvedre o de L&#8217;Horta Sur a la provincia de Valencia. Solo 3 centros en la provincia de Valencia disponen de aulas\u00a0CYL, un n\u00famero insuficiente si lo comparamos con las aulas\u00a0CYL\u00a0que hay operativas en educaci\u00f3n primaria. Qu\u00e9 pasa con estos ni\u00f1os y ni\u00f1as y las necesidades educativas de las cuales no desaparecen cuando cambian de etapa?<br \/>\nEstas son algunas preguntas que las familias de la escuela p\u00fablica nos hagamos despu\u00e9s de comprobar como es el d\u00eda a d\u00eda de un alumno con necesidades especiales en los colegios e institutos p\u00fablicos.<br \/>\nLa inclusi\u00f3n en las aulas es un tema muy importante para las familias porque afecta al desarrollo de nuestros hijos e hijas en todas sus vertientes. Por eso, no entendemos como la Administraci\u00f3n nos hace llegar tarde la normativa que regula la atenci\u00f3n que nuestros hijos e hijas, con necesidades especiales, recibir\u00e1n. Volvemos a informarnos que habr\u00e1 una nueva orden sobre inclusi\u00f3n a trav\u00e9s otras v\u00edas que no son las oficiales, lo cual impide que las familias de la escuela p\u00fablica puedan participar en la misma aportando su perspectiva desde el conocimiento que tienen del funcionamiento de sus hijos a casa. La verdadera inclusi\u00f3n en las aulas empieza en casa y creemos que el centro educativo y las familias tienen que trabajar juntos para conseguir que cada alumno y alumna llego a ser todo el que puede ser con garant\u00edas y recursos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La junta directiva se reuni\u00f3 este fin de semana para tratar temas que preocupan a las familias de la escuela p\u00fablica. Como punto central, la inclusi\u00f3n y la nueva ley.\u00a0Queremos una escuela inclusiva real. Desde de la Confederaci\u00f3n Gonzalo\u00a0Anaya consideramos que todos los ni\u00f1os y ni\u00f1as tienen derecho a una educaci\u00f3n p\u00fablica de calidad. Las asociaciones de padres y madres nos hacen llegar quejas concretas sobre la falta de recursos en los centros ordinarios para atender los que necesitan m\u00e1s apoyos. Uno de los puntos en los cuales hemos insistido en los \u00faltimos a\u00f1os es la falta de educadores para las aulas\u00a0CYL\u00a0en las tres provincias. Los plazos para cubrir las plazas son demasiado largos para unos ni\u00f1os y ni\u00f1as que necesitan atenci\u00f3n contin\u00faa. Adem\u00e1s, el alta rotaci\u00f3n de los profesionales que est\u00e1n en estas aulas hace dif\u00edcil el avance del alumnado, m\u00e1xime cuando la mayor\u00eda se encuentran dentro del trastorno del espectro autista, y precisamente el que m\u00e1s necesitan son rutinas y un personal estable para aportarlos seguridad y poder avanzar. \u201cLa integraci\u00f3n del\u00a0alumnado que necesita m\u00e1s apoyo no puede quedarse escrito en un papel como es el decreto y la nueva orden de inclusi\u00f3n, tiene que ser real en [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":6912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[54],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La junta, trabajando por la escuela inclusiva | Gonzalo Anaya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La junta, trabajando por la escuela inclusiva | Gonzalo Anaya\" \/>\n<meta property=\"og:description\" content=\"La junta directiva se reuni\u00f3 este fin de semana para tratar temas que preocupan a las familias de la escuela p\u00fablica. Como punto central, la inclusi\u00f3n y la nueva ley.\u00a0Queremos una escuela inclusiva real. Desde de la Confederaci\u00f3n Gonzalo\u00a0Anaya consideramos que todos los ni\u00f1os y ni\u00f1as tienen derecho a una educaci\u00f3n p\u00fablica de calidad. Las asociaciones de padres y madres nos hacen llegar quejas concretas sobre la falta de recursos en los centros ordinarios para atender los que necesitan m\u00e1s apoyos. Uno de los puntos en los cuales hemos insistido en los \u00faltimos a\u00f1os es la falta de educadores para las aulas\u00a0CYL\u00a0en las tres provincias. Los plazos para cubrir las plazas son demasiado largos para unos ni\u00f1os y ni\u00f1as que necesitan atenci\u00f3n contin\u00faa. Adem\u00e1s, el alta rotaci\u00f3n de los profesionales que est\u00e1n en estas aulas hace dif\u00edcil el avance del alumnado, m\u00e1xime cuando la mayor\u00eda se encuentran dentro del trastorno del espectro autista, y precisamente el que m\u00e1s necesitan son rutinas y un personal estable para aportarlos seguridad y poder avanzar. \u201cLa integraci\u00f3n del\u00a0alumnado que necesita m\u00e1s apoyo no puede quedarse escrito en un papel como es el decreto y la nueva orden de inclusi\u00f3n, tiene que ser real en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Gonzalo Anaya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/confederacio.gonzaloanaya\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-05T12:30:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2019\/02\/REUNIO-JUNTA-FEBRER-2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gonzalo Anaya\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gonzalo Anaya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gonzaloanaya.com\/#website\",\"url\":\"https:\/\/www.gonzaloanaya.com\/\",\"name\":\"Gonzalo Anaya\",\"description\":\"Confederaci\u00f3n de Asociaciones de Padres y Madres de Alumnos de la Comunidad Valenciana \\\"Gonzalo Anaya\\\" \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gonzaloanaya.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#primaryimage\",\"url\":\"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2019\/02\/REUNIO-JUNTA-FEBRER-2019.jpg\",\"contentUrl\":\"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2019\/02\/REUNIO-JUNTA-FEBRER-2019.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#webpage\",\"url\":\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/\",\"name\":\"La junta, trabajando por la escuela inclusiva | Gonzalo Anaya\",\"isPartOf\":{\"@id\":\"https:\/\/www.gonzaloanaya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#primaryimage\"},\"datePublished\":\"2019-02-05T12:30:40+00:00\",\"dateModified\":\"2019-02-05T12:30:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/d8c15b9dc3faa865aedb2546bd9f80b8\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"http:\/\/www.gonzaloanaya.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La junta, trabajando por la escuela inclusiva\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/d8c15b9dc3faa865aedb2546bd9f80b8\",\"name\":\"Gonzalo Anaya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/f76811ed77bbc23341618522f4177145?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/f76811ed77bbc23341618522f4177145?s=96&d=mm&r=g\",\"caption\":\"Gonzalo Anaya\"},\"sameAs\":[\"http:\/\/www.gonzaloanaya.com\"],\"url\":\"http:\/\/www.gonzaloanaya.com\/es\/author\/gonzalo-anaya\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La junta, trabajando por la escuela inclusiva | Gonzalo Anaya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/","og_locale":"es_ES","og_type":"article","og_title":"La junta, trabajando por la escuela inclusiva | Gonzalo Anaya","og_description":"La junta directiva se reuni\u00f3 este fin de semana para tratar temas que preocupan a las familias de la escuela p\u00fablica. Como punto central, la inclusi\u00f3n y la nueva ley.\u00a0Queremos una escuela inclusiva real. Desde de la Confederaci\u00f3n Gonzalo\u00a0Anaya consideramos que todos los ni\u00f1os y ni\u00f1as tienen derecho a una educaci\u00f3n p\u00fablica de calidad. Las asociaciones de padres y madres nos hacen llegar quejas concretas sobre la falta de recursos en los centros ordinarios para atender los que necesitan m\u00e1s apoyos. Uno de los puntos en los cuales hemos insistido en los \u00faltimos a\u00f1os es la falta de educadores para las aulas\u00a0CYL\u00a0en las tres provincias. Los plazos para cubrir las plazas son demasiado largos para unos ni\u00f1os y ni\u00f1as que necesitan atenci\u00f3n contin\u00faa. Adem\u00e1s, el alta rotaci\u00f3n de los profesionales que est\u00e1n en estas aulas hace dif\u00edcil el avance del alumnado, m\u00e1xime cuando la mayor\u00eda se encuentran dentro del trastorno del espectro autista, y precisamente el que m\u00e1s necesitan son rutinas y un personal estable para aportarlos seguridad y poder avanzar. \u201cLa integraci\u00f3n del\u00a0alumnado que necesita m\u00e1s apoyo no puede quedarse escrito en un papel como es el decreto y la nueva orden de inclusi\u00f3n, tiene que ser real en [&hellip;]","og_url":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/","og_site_name":"Gonzalo Anaya","article_publisher":"https:\/\/www.facebook.com\/confederacio.gonzaloanaya","article_published_time":"2019-02-05T12:30:40+00:00","og_image":[{"width":1600,"height":1200,"url":"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2019\/02\/REUNIO-JUNTA-FEBRER-2019.jpg","type":"image\/jpeg"}],"author":"Gonzalo Anaya","twitter_card":"summary","twitter_misc":{"Escrito por":"Gonzalo Anaya","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.gonzaloanaya.com\/#website","url":"https:\/\/www.gonzaloanaya.com\/","name":"Gonzalo Anaya","description":"Confederaci\u00f3n de Asociaciones de Padres y Madres de Alumnos de la Comunidad Valenciana \"Gonzalo Anaya\" ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gonzaloanaya.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#primaryimage","url":"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2019\/02\/REUNIO-JUNTA-FEBRER-2019.jpg","contentUrl":"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2019\/02\/REUNIO-JUNTA-FEBRER-2019.jpg","width":1600,"height":1200},{"@type":"WebPage","@id":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#webpage","url":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/","name":"La junta, trabajando por la escuela inclusiva | Gonzalo Anaya","isPartOf":{"@id":"https:\/\/www.gonzaloanaya.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#primaryimage"},"datePublished":"2019-02-05T12:30:40+00:00","dateModified":"2019-02-05T12:30:40+00:00","author":{"@id":"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/d8c15b9dc3faa865aedb2546bd9f80b8"},"breadcrumb":{"@id":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.gonzaloanaya.com\/es\/2019\/02\/05\/junta-trabajando-por-escuela-inclusiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"http:\/\/www.gonzaloanaya.com\/es\/"},{"@type":"ListItem","position":2,"name":"La junta, trabajando por la escuela inclusiva"}]},{"@type":"Person","@id":"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/d8c15b9dc3faa865aedb2546bd9f80b8","name":"Gonzalo Anaya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/f76811ed77bbc23341618522f4177145?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/f76811ed77bbc23341618522f4177145?s=96&d=mm&r=g","caption":"Gonzalo Anaya"},"sameAs":["http:\/\/www.gonzaloanaya.com"],"url":"http:\/\/www.gonzaloanaya.com\/es\/author\/gonzalo-anaya\/"}]}},"_links":{"self":[{"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/posts\/6916"}],"collection":[{"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/comments?post=6916"}],"version-history":[{"count":1,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/posts\/6916\/revisions"}],"predecessor-version":[{"id":6917,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/posts\/6916\/revisions\/6917"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/media\/6912"}],"wp:attachment":[{"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/media?parent=6916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/categories?post=6916"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/tags?post=6916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}