{"id":11085,"date":"2023-12-04T17:52:14","date_gmt":"2023-12-04T16:52:14","guid":{"rendered":"http:\/\/www.gonzaloanaya.com\/?p=11085"},"modified":"2023-12-04T17:54:08","modified_gmt":"2023-12-04T16:54:08","slug":"la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon","status":"publish","type":"post","link":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/","title":{"rendered":"La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n"},"content":{"rendered":"\n<p>\u2022 Rub\u00e9n Pacheco: \u201cEs falso que las familias ganemos en libertad de elecci\u00f3n de centro porque la admisi\u00f3n de zona \u00fanica solo sirve para que los centros concertados seleccionen el alumnado y para reforzar los centres guetos\u201d.<\/p>\n\n\n\n<p>\u2022 La organizaci\u00f3n mayoritaria de AMPA lamenta que el nuevo Consejo (PP-VOX) no quiera avanzar en igualdad de oportunidades para el alumnado valenciano al romper las zonas escolares e ir en contra de las ventajas de una escuela diversa y plural donde educar a hijas e hijos, que solo hacen posibles medidas como las zonas escolares y la reserva de plazas, de entre otras medidas, que aseguran la distribuci\u00f3n equilibrada del alumnado en todos los centros educativos.<\/p>\n\n\n\n<p>[Val\u00e8ncia, 4\/12\/2023]. Para la Confederaci\u00f3n de AMPA Gonzalo Anaya eliminar las zonas escolares en la admisi\u00f3n de los alumnos va en contra en la libertad de elecci\u00f3n de centro de las familias y solo favorece la selecci\u00f3n de los alumnos y de las familias de determinados centros educativos. Esta l\u00ednea para la Confederaci\u00f3n Gonzalo Anaya es \u201caltamente segregadora\u201d y provoca, adem\u00e1s, que el alumnado se concentre en unos centros educativos en detrimento de los otros que pueden perder matr\u00edcula y, por lo tanto, aulas y maestras.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"769\" height=\"1024\" src=\"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-769x1024.jpg\" alt=\"\" class=\"wp-image-11087\" srcset=\"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-769x1024.jpg 769w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-225x300.jpg 225w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-768x1023.jpg 768w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-1153x1536.jpg 1153w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-1538x2048.jpg 1538w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-110x146.jpg 110w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-38x50.jpg 38w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-56x75.jpg 56w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950-300x400.jpg 300w, http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950.jpg 1922w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/><\/figure>\n\n\n\n<p><br>\u201cEsto no es bueno para el alumnado en conjunto como tampoco para la educaci\u00f3n p\u00fablica que acaba sufriendo los recortes\u201d, ha destacado Rub\u00e9n Pacheco, presidente de la Confederaci\u00f3n Gonzalo Anaya qui\u00e9n se\u00f1ala que \u201cestos cambios previstos para el pr\u00f3ximo decreto de admisi\u00f3n escolar no ayudan en nada a la libertad de elecci\u00f3n de centros de las familias, ni mejoran la educaci\u00f3n de hijas e hijos en conjunto\u201d.<br><br>Adem\u00e1s, la zona \u00fanica provoca desplazamientos innecesarios en veh\u00edculos privados del alumnado con todo el caos y contaminaci\u00f3n para las ciudades, mientras que las zonas escolares favorecen que los ni\u00f1os y las ni\u00f1as se escolarizan en su barrio; un espacio enmarcado en su entorno m\u00e1s pr\u00f3ximo y en la comunidad en la cual viven, criterio principal de las familias en la hora de elegir escuela.<br><br><strong>Centros guetos<\/strong><\/p>\n\n\n\n<p><br>Desde la Confederaci\u00f3n Gonzalo Anaya afirmamos que cuando se aplican medidas como la zona \u00fanica y no hay reserva de plazas, el sistema educativo acaba segregando la infancia en funci\u00f3n de las posibilidades econ\u00f3micas, creando los centros de tipos A y los centros de tipos B; se refuerzan tambi\u00e9n los centros guetos y esto es incumplir un principio constitucional que es la igualdad de oportunidades.<\/p>\n\n\n\n<p><br>Advierten que en otras autonom\u00edas o en las otras etapas pol\u00edticas, la zona \u00fanica ha sido la medida que ha servido como antesala a la privatizaci\u00f3n de la educaci\u00f3n, fundamentada en t\u00e9rminos mercantiles, de oferta y demanda y esto en educaci\u00f3n solo sirve para segregar el alumnado y no mejora en nada la educaci\u00f3n de todas y todos. \u201cLa zona \u00fanica solo favorece en los centros concertados donde las administraciones acaban para transferir recursos econ\u00f3micos de la educaci\u00f3n p\u00fablica hacia la privada, tratando los ni\u00f1os y las ni\u00f1as como si fueron clientes y haciendo que las familias acaban para pagar el derecho a la educaci\u00f3n dos veces con los impuestos y con las cuotas encubiertas que cobran los concertados\u201d, ha destacado Pacheco.<\/p>\n\n\n\n<p>Seg\u00fan la organizaci\u00f3n de AMPA, estas l\u00edneas consultadas desvirt\u00faan los avances en admisi\u00f3n escolar y dejan atr\u00e1s el modelo de escuela diversa y plural y todo el potencial educativo que tiene la diversidad a las aulas, tal como indican todos los estudios (OCDE).<\/p>\n\n\n\n<p>\u201cLas aulas tiene que ser un espejo de la sociedad y ense\u00f1ar a vivir y a convivir en un mundo diverso donde todas las personas tenemos las mismas oportunidades\u201d y por eso tanto los centros p\u00fablicos como los concertados tienen la obligaci\u00f3n de acoger toda la diversidad del alumnado sin diferencias, garantizando el acceso y distribuyendo el alumnado con equilibrio y planificaci\u00f3n, ha destacado Pacheco.<\/p>\n\n\n\n<p>Sobre las l\u00edneas que apuntan pol\u00edticas de admisi\u00f3n para el alumnado migrante y la admisi\u00f3n en educaci\u00f3n especial, la organizaci\u00f3n se reserva para tener el borrador del decreto y conocer en detalle el articulado del proyecto de Decreto de Admisi\u00f3n. Aun as\u00ed, reivindican recursos especializados en todos los centros educativos p\u00fablicos y concertados para acoger el alumnado en toda su diversidad y hacer posible la aplicaci\u00f3n del Decreto de inclusi\u00f3n y la Orden de respuesta educativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Rub\u00e9n Pacheco: \u201cEs falso que las familias ganemos en libertad de elecci\u00f3n de centro porque la admisi\u00f3n de zona \u00fanica solo sirve para que los centros concertados seleccionen el alumnado y para reforzar los centres guetos\u201d. \u2022 La organizaci\u00f3n mayoritaria de AMPA lamenta que el nuevo Consejo (PP-VOX) no quiera avanzar en igualdad de oportunidades para el alumnado valenciano al romper las zonas escolares e ir en contra de las ventajas de una escuela diversa y plural donde educar a hijas e hijos, que solo hacen posibles medidas como las zonas escolares y la reserva de plazas, de entre otras medidas, que aseguran la distribuci\u00f3n equilibrada del alumnado en todos los centros educativos. [Val\u00e8ncia, 4\/12\/2023]. Para la Confederaci\u00f3n de AMPA Gonzalo Anaya eliminar las zonas escolares en la admisi\u00f3n de los alumnos va en contra en la libertad de elecci\u00f3n de centro de las familias y solo favorece la selecci\u00f3n de los alumnos y de las familias de determinados centros educativos. Esta l\u00ednea para la Confederaci\u00f3n Gonzalo Anaya es \u201caltamente segregadora\u201d y provoca, adem\u00e1s, que el alumnado se concentre en unos centros educativos en detrimento de los otros que pueden perder matr\u00edcula y, por lo tanto, aulas y maestras. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":11087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[54],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n | Gonzalo Anaya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n | Gonzalo Anaya\" \/>\n<meta property=\"og:description\" content=\"\u2022 Rub\u00e9n Pacheco: \u201cEs falso que las familias ganemos en libertad de elecci\u00f3n de centro porque la admisi\u00f3n de zona \u00fanica solo sirve para que los centros concertados seleccionen el alumnado y para reforzar los centres guetos\u201d. \u2022 La organizaci\u00f3n mayoritaria de AMPA lamenta que el nuevo Consejo (PP-VOX) no quiera avanzar en igualdad de oportunidades para el alumnado valenciano al romper las zonas escolares e ir en contra de las ventajas de una escuela diversa y plural donde educar a hijas e hijos, que solo hacen posibles medidas como las zonas escolares y la reserva de plazas, de entre otras medidas, que aseguran la distribuci\u00f3n equilibrada del alumnado en todos los centros educativos. [Val\u00e8ncia, 4\/12\/2023]. Para la Confederaci\u00f3n de AMPA Gonzalo Anaya eliminar las zonas escolares en la admisi\u00f3n de los alumnos va en contra en la libertad de elecci\u00f3n de centro de las familias y solo favorece la selecci\u00f3n de los alumnos y de las familias de determinados centros educativos. Esta l\u00ednea para la Confederaci\u00f3n Gonzalo Anaya es \u201caltamente segregadora\u201d y provoca, adem\u00e1s, que el alumnado se concentre en unos centros educativos en detrimento de los otros que pueden perder matr\u00edcula y, por lo tanto, aulas y maestras. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/\" \/>\n<meta property=\"og:site_name\" content=\"Gonzalo Anaya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/confederacio.gonzaloanaya\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T16:52:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T16:54:08+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1922\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gonzalo Anaya\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gonzalo Anaya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gonzaloanaya.com\/#website\",\"url\":\"https:\/\/www.gonzaloanaya.com\/\",\"name\":\"Gonzalo Anaya\",\"description\":\"Confederaci\u00f3n de Asociaciones de Padres y Madres de Alumnos de la Comunidad Valenciana \\\"Gonzalo Anaya\\\" \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gonzaloanaya.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#primaryimage\",\"url\":\"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950.jpg\",\"contentUrl\":\"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950.jpg\",\"width\":1922,\"height\":2560},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#webpage\",\"url\":\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/\",\"name\":\"La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n | Gonzalo Anaya\",\"isPartOf\":{\"@id\":\"https:\/\/www.gonzaloanaya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#primaryimage\"},\"datePublished\":\"2023-12-04T16:52:14+00:00\",\"dateModified\":\"2023-12-04T16:54:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/d8c15b9dc3faa865aedb2546bd9f80b8\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"http:\/\/www.gonzaloanaya.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/d8c15b9dc3faa865aedb2546bd9f80b8\",\"name\":\"Gonzalo Anaya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/f76811ed77bbc23341618522f4177145?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/f76811ed77bbc23341618522f4177145?s=96&d=mm&r=g\",\"caption\":\"Gonzalo Anaya\"},\"sameAs\":[\"http:\/\/www.gonzaloanaya.com\"],\"url\":\"http:\/\/www.gonzaloanaya.com\/es\/author\/gonzalo-anaya\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n | Gonzalo Anaya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/","og_locale":"es_ES","og_type":"article","og_title":"La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n | Gonzalo Anaya","og_description":"\u2022 Rub\u00e9n Pacheco: \u201cEs falso que las familias ganemos en libertad de elecci\u00f3n de centro porque la admisi\u00f3n de zona \u00fanica solo sirve para que los centros concertados seleccionen el alumnado y para reforzar los centres guetos\u201d. \u2022 La organizaci\u00f3n mayoritaria de AMPA lamenta que el nuevo Consejo (PP-VOX) no quiera avanzar en igualdad de oportunidades para el alumnado valenciano al romper las zonas escolares e ir en contra de las ventajas de una escuela diversa y plural donde educar a hijas e hijos, que solo hacen posibles medidas como las zonas escolares y la reserva de plazas, de entre otras medidas, que aseguran la distribuci\u00f3n equilibrada del alumnado en todos los centros educativos. [Val\u00e8ncia, 4\/12\/2023]. Para la Confederaci\u00f3n de AMPA Gonzalo Anaya eliminar las zonas escolares en la admisi\u00f3n de los alumnos va en contra en la libertad de elecci\u00f3n de centro de las familias y solo favorece la selecci\u00f3n de los alumnos y de las familias de determinados centros educativos. Esta l\u00ednea para la Confederaci\u00f3n Gonzalo Anaya es \u201caltamente segregadora\u201d y provoca, adem\u00e1s, que el alumnado se concentre en unos centros educativos en detrimento de los otros que pueden perder matr\u00edcula y, por lo tanto, aulas y maestras. [&hellip;]","og_url":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/","og_site_name":"Gonzalo Anaya","article_publisher":"https:\/\/www.facebook.com\/confederacio.gonzaloanaya","article_published_time":"2023-12-04T16:52:14+00:00","article_modified_time":"2023-12-04T16:54:08+00:00","og_image":[{"width":1922,"height":2560,"url":"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950.jpg","type":"image\/jpeg"}],"author":"Gonzalo Anaya","twitter_card":"summary","twitter_misc":{"Escrito por":"Gonzalo Anaya","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.gonzaloanaya.com\/#website","url":"https:\/\/www.gonzaloanaya.com\/","name":"Gonzalo Anaya","description":"Confederaci\u00f3n de Asociaciones de Padres y Madres de Alumnos de la Comunidad Valenciana \"Gonzalo Anaya\" ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gonzaloanaya.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#primaryimage","url":"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950.jpg","contentUrl":"http:\/\/www.gonzaloanaya.com\/wp-content\/uploads\/2023\/12\/rubenpacheco_solangegodoy-scaled-e1701708622950.jpg","width":1922,"height":2560},{"@type":"WebPage","@id":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#webpage","url":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/","name":"La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n | Gonzalo Anaya","isPartOf":{"@id":"https:\/\/www.gonzaloanaya.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#primaryimage"},"datePublished":"2023-12-04T16:52:14+00:00","dateModified":"2023-12-04T16:54:08+00:00","author":{"@id":"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/d8c15b9dc3faa865aedb2546bd9f80b8"},"breadcrumb":{"@id":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.gonzaloanaya.com\/es\/2023\/12\/04\/la-confederacio-gonzalo-anaya-califica-como-altamente-segregadora-la-admision-de-zona-unica-de-mazon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"http:\/\/www.gonzaloanaya.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Confederaci\u00f3 Gonzalo Anaya califica como \u201caltamente segregadora\u201d la admisi\u00f3n de zona \u00fanica de Maz\u00f3n"}]},{"@type":"Person","@id":"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/d8c15b9dc3faa865aedb2546bd9f80b8","name":"Gonzalo Anaya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gonzaloanaya.com\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/f76811ed77bbc23341618522f4177145?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/f76811ed77bbc23341618522f4177145?s=96&d=mm&r=g","caption":"Gonzalo Anaya"},"sameAs":["http:\/\/www.gonzaloanaya.com"],"url":"http:\/\/www.gonzaloanaya.com\/es\/author\/gonzalo-anaya\/"}]}},"_links":{"self":[{"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/posts\/11085"}],"collection":[{"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/comments?post=11085"}],"version-history":[{"count":2,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/posts\/11085\/revisions"}],"predecessor-version":[{"id":11089,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/posts\/11085\/revisions\/11089"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/media\/11087"}],"wp:attachment":[{"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/media?parent=11085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/categories?post=11085"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.gonzaloanaya.com\/es\/wp-json\/wp\/v2\/tags?post=11085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}